{"id":607,"count":2,"description":"","link":"https:\/\/socialmedialab.ca\/beta\/tag\/data-science\/","name":"data science","slug":"data-science","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags\/607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts?tags=607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}