{"id":599,"count":1,"description":"","link":"https:\/\/socialmedialab.ca\/beta\/tag\/media-credibility\/","name":"media credibility","slug":"media-credibility","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts?tags=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}