{"id":510,"count":11,"description":"","link":"https:\/\/socialmedialab.ca\/beta\/tag\/polidashboard\/","name":"Polidashboard","slug":"polidashboard","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags\/510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts?tags=510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}