{"id":12557,"date":"2018-02-25T23:20:18","date_gmt":"2018-02-25T23:20:18","guid":{"rendered":"https:\/\/socialmedialab.ca\/beta\/?p=12557"},"modified":"2024-12-11T00:59:41","modified_gmt":"2024-12-11T00:59:41","slug":"state-of-social-media-in-canada","status":"publish","type":"post","link":"https:\/\/socialmedialab.ca\/beta\/2018\/02\/25\/state-of-social-media-in-canada\/","title":{"rendered":"The State of Social Media in Canada 2017: A New Report From @SMLabTO"},"content":{"rendered":"<h2><span style=\"font-weight: 400;\"><i>Survey reveals the state of social media in Canada and finds 94% of adult Canadian internet users have at least one social media account.<\/i><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Despite concerns fake news is flooding the Internet, Canadians&#8217; love affair with social media shows no signs of slowing. A new <\/span><a href=\"https:\/\/borealisdata.ca\/dataset.xhtml?persistentId=doi:10.5683\/SP\/AL8Z6R\"><span style=\"font-weight: 400;\">survey<\/span><\/a><span style=\"font-weight: 400;\">\u00a0released today by the Social Media Lab (<a href=\"https:\/\/twitter.com\/SMLabTO\">@SMLabTO<\/a>), an interdisciplinary research lab at Toronto Metropolitan&#8217;s <\/span>Ted Rogers School of Management (<a href=\"https:\/\/twitter.com\/TRSMRyersonU\">@TRSMRyersonU<\/a>), offers an in-depth look into the state of social media in Canada. It found that 94% of adults who use the Internet have at least one social media account.<span style=\"font-weight: 400;\"><i><a href=\"https:\/\/borealisdata.ca\/dataset.xhtml?persistentId=doi:10.5683\/SP\/AL8Z6R\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignnone wp-image-12553 size-full\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2.png\" alt=\"\" width=\"1260\" height=\"420\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2.png 1260w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2-300x100.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2-768x256.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2-600x200.png 600w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2-696x232.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Report_Cover2-1068x356.png 1068w\" sizes=\"(max-width: 1260px) 100vw, 1260px\" \/><\/a><\/i><\/span><span style=\"font-weight: 400;\">The study surveyed 1,500 Canadians in 2017 using quota sampling by age, gender, and geographical region to match the distributions in the 2016 Statistics Canada Census. Results showed, Facebook was the most popular social media platform with 8<\/span><span style=\"font-weight: 400;\">4% of online Canadian adults reporting they have a Facebook account. And despite concerns that young people are leaving the social networking giant, the study found 95% of young adults aged 18-24 were on Facebook.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Photo-sharing favourites, Pinterest and Instagram, were the fifth and sixth most popular social media platforms with 38% and 37%, respectively, of online Canadians reporting an account. Reddit was the least popular platform of those included in the report with only 9% of online Canadian adults using the discussion website.<\/span><\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/borealisdata.ca\/dataset.xhtml?persistentId=doi:10.5683\/SP\/AL8Z6R\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Download the report<\/strong><\/a><\/h1>\n<div id='gallery-1' class='gallery galleryid-12557 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Facebook.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/YouTube.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/LinkedIn.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Twitter.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Pinterest.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Instagram.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Snapchat2.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Tumblr.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-300x300.png 300w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-150x150.png 150w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-768x768.png 768w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-500x500.png 500w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-696x696.png 696w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-1068x1068.png 1068w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit-420x420.png 420w, https:\/\/socialmedialab.ca\/beta\/wp-content\/uploads\/2018\/02\/Reddit.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><em><span style=\"font-weight: 400;\">The report was produced by the Toronto Metropolitan University Social Media Lab, with funding support from the <a href=\"https:\/\/www.chairs-chaires.gc.ca\/home-accueil-eng.aspx\">Canada Research Chairs Program<\/a> (PI: Gruzd) and the Ted Rogers School of Management. It is co-authored <\/span><span style=\"font-weight: 400;\">by <a href=\"https:\/\/twitter.com\/gruzd\" target=\"_blank\" rel=\"noopener noreferrer\">Anatoliy Gruzd<\/a>, <a href=\"https:\/\/twitter.com\/jacobsonjenna\" target=\"_blank\" rel=\"noopener noreferrer\">Jenna Jacobson<\/a>, <a href=\"https:\/\/twitter.com\/PhMai\">Philip Mai<\/a> <i>at Toronto Metropolitan University,<\/i>\u00a0and <a href=\"https:\/\/twitter.com\/lizdubois\">Elizabeth Dubois\u00a0<\/a><\/span><\/em><i><span style=\"font-weight: 400;\">at the University of Ottawa. <\/span><\/i><em><span style=\"font-weight: 400;\">The aim of the report is to address the lack of data on social media adoption and use trends in Canada, and it is inspired by the amazing work done\u00a0<\/span><span style=\"font-weight: 400;\">by the\u00a0<\/span><a href=\"https:\/\/www.pewresearch.org\/topic\/internet-technology\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pew\u00a0Research Center&#8217;s\u00a0Internet\u00a0&amp; American Life Project<\/a>, a nonprofit, nonpartisan research organization in the United States.\u00a0<\/em><\/p>\n<p>Press and media inquiries:<br \/>\nPhilip Mai<br \/>\nDirector of Business and Communications<br \/>\n416-979-5000 ext. 3509<br \/>\nPhilip.mai@ryerson.ca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Survey reveals the state of social media in Canada and finds 94% of adult Canadian internet users have at least one social media account. Despite concerns fake news is flooding the Internet, Canadians&#8217; love affair with social media shows no signs of slowing. A new survey\u00a0released today by the Social Media Lab (@SMLabTO), an interdisciplinary [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,490,489,44,265],"tags":[426,448,447],"class_list":{"0":"post-12557","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-announcements","8":"category-online-communities","9":"category-org-soc-med-use","10":"category-publishing","11":"category-research","12":"tag-426","13":"tag-social-media-adoption","14":"tag-social-media-stats"},"_links":{"self":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts\/12557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/comments?post=12557"}],"version-history":[{"count":26,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts\/12557\/revisions"}],"predecessor-version":[{"id":21505,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/posts\/12557\/revisions\/21505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/media\/12594"}],"wp:attachment":[{"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/media?parent=12557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/categories?post=12557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socialmedialab.ca\/beta\/wp-json\/wp\/v2\/tags?post=12557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}